<br />
<b>Warning</b>:  Creating default object from empty value in <b>/home/u544005531/domains/valeriapelka.com/public_html/estudiosmusicales/wp-content/plugins/nimble-portfolio/admin/redux-framework/inc/class.redux_filesystem.php</b> on line <b>29</b><br />
{"id":39,"date":"2021-08-05T14:12:42","date_gmt":"2021-08-05T14:12:42","guid":{"rendered":"http:\/\/estudiosmusicales.valeriapelka.com\/?page_id=39"},"modified":"2024-12-02T20:31:51","modified_gmt":"2024-12-02T20:31:51","slug":"bio","status":"publish","type":"page","link":"https:\/\/estudiosmusicales.valeriapelka.com\/index.php\/bio\/","title":{"rendered":"BIO"},"content":{"rendered":"<h4><span style=\"font-weight: 400;\">UNA VIDA DEDICADA A EXPLORAR LAS M\u00c1S DIVERSAS EST\u00c9TICAS MUSlCALES<\/span><\/h4>\n<h4><span style=\"font-weight: 400;\">Comenc\u00e9 mi carrera como guitarrista de m\u00fasica popular &#8211; aunque tambi\u00e9n curs\u00e9 estudios de m\u00fasica cl\u00e1sica &#8211; especializ\u00e1ndome en estilo fusi\u00f3n. Me gradu\u00e9 en la carrera de m\u00fasico int\u00e9rprete de guitarra en la Escuela de M\u00fasica Popular del Sindicato Argentino de M\u00fasicos. Fueron a\u00f1os de mucho descubrimiento, y de compartir m\u00fasica con profesores y compa\u00f1eros maravillosos. Por esos tiempos mis m\u00e1ximos referentes eran m\u00fasicos tales como Pat Metheny, Mike Stern, Miles Davis, Keith Jarrett y Chick Corea entre muchos m\u00e1s.<\/span><\/h4>\n<h4><span style=\"font-weight: 400;\">Al pasar los a\u00f1os me aboqu\u00e9 a una de las pasiones que me acompa\u00f1aba desde ni\u00f1a: cantar y componer mis propias canciones.\u00a0 Ya contaba ya con m\u00e1s de 100 canciones cuando tom\u00e9 la decisi\u00f3n de emprender la hermosa tarea de componer y producir mi primer disco propio. Cantautores de mi pa\u00eds como Fito P\u00e1ez, Gustavo Cerati, y extranjeros como Djavan, Marisa Monte, Lenine, Maria Bethania, eran algunos de mis modelos. Pude darme el gusto de producir mi disco de manera independiente, armar mi banda y salir a presentar &#8220;El tiempo borrar\u00e1&#8221; por gran cantidad de bares, centros culturales y teatros de mi ciudad, Buenos Aires, y de algunas provincias del interior del pa\u00eds.<\/span><\/h4>\n<h4><span style=\"font-weight: 400;\">Dado que soy una persona muy inquieta, encontr\u00e9 que mi deseo se iba moviendo nuevamente hacia otras posibilidades de la m\u00fasica, otra de mis pasiones tambi\u00e9n iniciada en mi edad m\u00e1s temprana.<\/span><\/h4>\n<h4><span style=\"font-weight: 400;\">Las m\u00fasicas de las series y pel\u00edculas que am\u00e9, dejaron huellas en m\u00ed y quise entonces aprender a escribir m\u00fasica orquestal, inspirada por el enorme talento de compositores como John Williams, Ennio Morricone, Nino Rota, Danny Elfman, John Barry, entre tantos otros.<\/span><\/h4>\n<h4><span style=\"font-weight: 400;\">Fue as\u00ed que decid\u00ed ingresar en la Universidad Nacional de las Artes a cursar la carrera de Composici\u00f3n. A partir de ese momento mi formaci\u00f3n se acrecent\u00f3 de manera exponencial, encontr\u00e9 en la universidad mucho m\u00e1s de lo que fui a buscar.<\/span><\/h4>\n<h4><span style=\"font-weight: 400;\">Mi espectro compositivo creci\u00f3 y se diversific\u00f3, teniendo la oportunidad de componer m\u00fasicas para escenas de pel\u00edculas, para videos documentales, para videojuegos, y m\u00fasicas de concierto con diversas est\u00e9ticas, desde el antiguo canon renacentista, hasta m\u00fasica aleatoria, m\u00fasica de masas y otras est\u00e9ticas contempor\u00e1neas.<\/span><\/h4>\n<h4><span style=\"font-weight: 400;\">Tuve la oportunidad de incursionar en la composici\u00f3n de fugas barrocas, obras para piano al estilos cl\u00e1sico, rom\u00e1ntico, impresionista, neocl\u00e1sico, atonal, dodecaf\u00f3nico. Sin duda un hermoso viaje exploratorio, recorriendo gran parte de la historia de la m\u00fasica occidental.<\/span><\/h4>\n<h4><span style=\"font-weight: 400;\">Y mientras tanto me d\u00ed a la tarea de encontrar mi propia voz, de buscar y construir una est\u00e9tica personal, que lleve impresas todas esas m\u00fasicas maravillosas que me llenaron y a\u00fan me llenan el alma.<\/span><\/h4>\n<h4><span style=\"font-weight: 400;\">Mi m\u00fasica tendr\u00e1 tambi\u00e9n un v\u00ednculo con la m\u00fasica de mi pa\u00eds &#8211; tintes tangueros y folkl\u00f3ricos &#8211; y de Latinoam\u00e9rica. As\u00ed como me permito dejarme influenciar por el jazz, el rock, la m\u00fasica popular brasile\u00f1a y muchas otras.<\/span><\/h4>\n<h4><span style=\"font-weight: 400;\">Mi intenci\u00f3n como compositora es unir las dos orillas &#8211; en lo personal no creo que est\u00e9n verdaderamente separadas &#8211; de la m\u00fasica acad\u00e9mica y la popular, as\u00ed como traer las est\u00e9ticas de las m\u00fasicas de otros tiempos a fusionarse con sonoridades m\u00e1s actuales.<\/span><\/h4>\n<h4><span style=\"font-weight: 400;\">En definitiva, una posible integraci\u00f3n de lo que fue, con lo que es y lo que puede llegar a ser.<\/span><\/h4>\n<p><img loading=\"lazy\" class=\" wp-image-40 aligncenter\" src=\"http:\/\/estudiosmusicales.valeriapelka.com\/wp-content\/uploads\/2021\/08\/USAR-ESTA-300x200.jpg\" alt=\"\" width=\"469\" height=\"312\" srcset=\"https:\/\/estudiosmusicales.valeriapelka.com\/wp-content\/uploads\/2021\/08\/USAR-ESTA-300x200.jpg 300w, https:\/\/estudiosmusicales.valeriapelka.com\/wp-content\/uploads\/2021\/08\/USAR-ESTA-1024x683.jpg 1024w, https:\/\/estudiosmusicales.valeriapelka.com\/wp-content\/uploads\/2021\/08\/USAR-ESTA-768x512.jpg 768w, https:\/\/estudiosmusicales.valeriapelka.com\/wp-content\/uploads\/2021\/08\/USAR-ESTA.jpg 1296w\" sizes=\"(max-width: 469px) 100vw, 469px\" \/><\/p>\n<h4><\/h4>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">FORMACI\u00d3N ACAD\u00c9MICA:<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Licenciada en Composici\u00f3n &#8211; Universidad Nacional de las Artes (UNA &#8211; Damus)\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Fernando Albinarrate &#8211; Composici\u00f3n y Armon\u00eda<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Pablo Freiberg &#8211; Composici\u00f3n<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Guillermo Pozzati &#8211; Composici\u00f3n<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Cecilia Pereyra &#8211; Composici\u00f3n<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Guillermo Zalcman &#8211; Orquestaci\u00f3n<\/span><\/p>\n<p>Gustavo Fontana &#8211; Direcci\u00f3n Orquestal<\/p>\n<p>Carlos David Jaimes &#8211; Direcci\u00f3n Orquestal<\/p>\n<p><span style=\"font-weight: 400;\">Rolando Budini &#8211; Contrapunto y Fuga<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Diego Gardiner &#8211; Contrapunto<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Gian Piero Luque &#8211; Armon\u00eda<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Carlos Lucero &#8211; Armon\u00eda<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Selva Ferrari &#8211; Audioperceptiva<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Eduardo Kacheli &#8211; Audioperceptiva<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Sandro Benedetto &#8211; M\u00fasica Incidental<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ariel Pirotti \u2013 Arreglos de Tango<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Tecnicatura en Guitarra &#8211; M\u00fasica Popular &#8211; Sindicato Argentino de M\u00fasicos (SADeM)\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Conservatorio Nacional L\u00f3pez Buchardo &#8211; Guitarra Cl\u00e1sica<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Juan Ben\u00edtez &#8211; Guitarra Fusi\u00f3n<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Pablo Bobrowicky &#8211; Guitarra Jazz<\/span><\/p>\n<p>&nbsp;<\/p>\n<h4 style=\"font-style: normal; letter-spacing: normal; text-align: center;\"><a href=\"https:\/\/es.valeriapelka.com\/\" target=\"_blank\" rel=\"noopener\">M\u00c1S INFORMACI\u00d3N SOBRE MI CARRERA COMO COMPOSITORA<\/a><\/h4>\n","protected":false},"excerpt":{"rendered":"<p>UNA VIDA DEDICADA A EXPLORAR LAS M\u00c1S DIVERSAS EST\u00c9TICAS MUSlCALES Comenc\u00e9 mi carrera como guitarrista de m\u00fasica popular &#8211; aunque tambi\u00e9n curs\u00e9 estudios de m\u00fasica [&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":831,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":""},"_links":{"self":[{"href":"https:\/\/estudiosmusicales.valeriapelka.com\/index.php\/wp-json\/wp\/v2\/pages\/39"}],"collection":[{"href":"https:\/\/estudiosmusicales.valeriapelka.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/estudiosmusicales.valeriapelka.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/estudiosmusicales.valeriapelka.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/estudiosmusicales.valeriapelka.com\/index.php\/wp-json\/wp\/v2\/comments?post=39"}],"version-history":[{"count":25,"href":"https:\/\/estudiosmusicales.valeriapelka.com\/index.php\/wp-json\/wp\/v2\/pages\/39\/revisions"}],"predecessor-version":[{"id":849,"href":"https:\/\/estudiosmusicales.valeriapelka.com\/index.php\/wp-json\/wp\/v2\/pages\/39\/revisions\/849"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/estudiosmusicales.valeriapelka.com\/index.php\/wp-json\/wp\/v2\/media\/831"}],"wp:attachment":[{"href":"https:\/\/estudiosmusicales.valeriapelka.com\/index.php\/wp-json\/wp\/v2\/media?parent=39"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}